{"id":802,"date":"2023-02-27T16:55:54","date_gmt":"2023-02-27T15:55:54","guid":{"rendered":"https:\/\/centre-babel.fr\/colloque-babel\/lieu\/"},"modified":"2023-07-26T08:26:15","modified_gmt":"2023-07-26T06:26:15","slug":"luogo","status":"publish","type":"page","link":"https:\/\/centre-babel.fr\/colloque-babel\/it\/luogo\/","title":{"rendered":"LUOGO"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3fof-5f286b13a3ebc266a33ff918a22f685b\">\n.avia-section.av-3fof-5f286b13a3ebc266a33ff918a22f685b{\nbackground-color:#80afa1;\nbackground-image:url(https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-centre-babel-colloque-2023.jpg);\nbackground-repeat:no-repeat;\nbackground-position:50% 50%;\nbackground-attachment:scroll;\nposition:relative;\n}\n.avia-section.av-3fof-5f286b13a3ebc266a33ff918a22f685b .avia-divider-svg-bottom svg{\nheight:43px;\nwidth:calc(132% + 1.3px);\nfill:#ffffff;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-3fof-5f286b13a3ebc266a33ff918a22f685b main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-full-stretch avia-bg-style-scroll av-minimum-height av-minimum-height-75 av-height-75  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='75' data-av_min_height_opt='75'><div class='avia-divider-svg avia-divider-svg-mountains avia-divider-svg-bottom avia-svg-original'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg><\/div><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-802'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-leo0txsh-f4ec3ca931f6f076ca5e7771efff33f8 av_one_full  avia-builder-el-1  avia-builder-el-no-sibling  first flex_column_div  '     ><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-len08271-6b31464367b1326c76f96d362f2b7a57 main_color avia-section-default avia-no-border-styling  avia-builder-el-2  el_after_av_section  el_before_av_one_full  avia-bg-style-scroll av-minimum-height av-minimum-height-75 av-height-75  container_wrap fullsize'   data-av_minimum_height_pc='75' data-av_min_height_opt='75'><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-802'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-wlr7-f10d15f7c89bc58d4ba1b375914732e0 sc-av_one_half av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-wlr7-f10d15f7c89bc58d4ba1b375914732e0\">\n.flex_column.av-wlr7-f10d15f7c89bc58d4ba1b375914732e0{\npadding:30px 30px 30px 30px;\nbackground-color:#f4f4f4;\n}\n<\/style>\n<div  class='flex_column av-wlr7-f10d15f7c89bc58d4ba1b375914732e0 av_one_half  avia-builder-el-3  el_before_av_one_half  avia-builder-el-first  first flex_column_table_cell av-equal-height-column av-align-middle  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-leo0paug-434648d249b11a67262d50fa94194750\">\n#top .av-special-heading.av-leo0paug-434648d249b11a67262d50fa94194750{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-leo0paug-434648d249b11a67262d50fa94194750 .av-special-heading-tag .heading-char{\nfont-size:57px;\ncolor:#f23232;\npadding-bottom:10px;\n}\n.av-special-heading.av-leo0paug-434648d249b11a67262d50fa94194750 .av-subheading{\nfont-size:25px;\n}\n<\/style>\n<div  class='av-special-heading av-leo0paug-434648d249b11a67262d50fa94194750 av-special-heading-h1 custom-color-heading blockquote elegant-quote elegant-centered  avia-builder-el-4  el_before_av_textblock  avia-builder-el-first  av-icon'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  ><span class='heading-char avia-font-entypo-fontello' aria-hidden='true' data-av_icon='\ue842' data-av_iconfont='entypo-fontello'><\/span><span class=\"heading-wrap\">Luogo<\/span><\/h1><div class='av-subheading av-subheading_below'><p>Centro internazionale di conferenze<br \/>\nUniversit\u00e0 La Sorbonne<br \/>\nPatio 44,<br \/>\n4 Pl. Jussieu 55,<br \/>\n75005 Parigi<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-len0rdpr-694e7385745d8f0bf79cad993e85de71\">\n#top .av_textblock_section.av-len0rdpr-694e7385745d8f0bf79cad993e85de71 .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-len0rdpr-694e7385745d8f0bf79cad993e85de71 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>Il CICSU si trova nel Campus Pierre e Marie Curie (4, place Jussieu), nel 5\u00b0 arrondissement di Parigi, nel cuore del Quartiere Latino.<\/strong><br \/>\n<strong>\u00c8 accessibile in auto e con i mezzi pubblici :<\/strong><\/p>\n<ul>\n<li>Metropolitana: linee 7 e 10 (fermata Jussieu)<\/li>\n<li>Autobus: percorsi 63, 89, 67, 86, 87<\/li>\n<li>Accesso gratuito al parcheggio del Campus Pierre et Marie Curie su richiesta e in base alla disponibilit\u00e0.<\/li>\n<\/ul>\n<\/div><\/section><br \/>\n<div id='av-masonry-1' class='av-masonry av-liuahbvs-d8130150f94c4839f74b0878b5dc9fa8 noHover av-fixed-size av-1px-gap av-hover-overlay- av-masonry-animation-active av-masonry-col-2 av-caption-always av-caption-style- av-masonry-gallery av-orientation-square ' data-post_id=\"802\"><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image '><\/div><a href=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel-1030x579.jpg\" data-srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel-1030x579.jpg 1030w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel-300x169.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel-768x432.jpg 768w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel-1536x864.jpg 1536w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel-1500x844.jpg 1500w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel-705x397.jpg 705w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel.jpg 1920w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"immagine Salle colloque centre babel\"  id='av-masonry-1-item-745' data-av-masonry-item='745' class='av-masonry-entry isotope-item post-745 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Salle colloque centre babel\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/06\/Salle-colloque-centre-babel-705x397.jpg);\"  title=\"Salle colloque centre babel\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/Campus-Pierre-et-Marie-Curie.jpg\" data-srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/Campus-Pierre-et-Marie-Curie.jpg 672w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/Campus-Pierre-et-Marie-Curie-219x300.jpg 219w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/Campus-Pierre-et-Marie-Curie-515x705.jpg 515w\" data-sizes=\"(max-width: 672px) 100vw, 672px\"  aria-label=\"immagine Campus Pierre et Marie Curie\"  id='av-masonry-1-item-715' data-av-masonry-item='715' class='av-masonry-entry isotope-item post-715 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Campus Pierre et Marie Curie\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/Campus-Pierre-et-Marie-Curie-515x705.jpg);\"  title=\"Campus Pierre et Marie Curie\" ><\/div><\/div><\/figure><\/a><!--end av-masonry entry--><\/div><\/div><\/p><\/div><div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-len0u4pg-7f2877b2d40110bc26f260075b775d69\">\n.flex_column.av-len0u4pg-7f2877b2d40110bc26f260075b775d69{\nbackground-color:#ffffff;\n}\n<\/style>\n<div  class='flex_column av-len0u4pg-7f2877b2d40110bc26f260075b775d69 av_one_half  avia-builder-el-7  el_after_av_one_half  avia-builder-el-last  flex_column_table_cell av-equal-height-column av-align-middle  '     ><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_2'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-802'><div class='entry-content-wrapper clearfix'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-liub7ein-e4454c550186162d8788251ae1613d89\">\n.flex_column.av-liub7ein-e4454c550186162d8788251ae1613d89{\nborder-width:2px;\nborder-color:#353535;\nborder-style:solid;\npadding:30px 30px 30px 30px;\nbackground-color:#f4f4f4;\n}\n<\/style>\n<div  class='flex_column av-liub7ein-e4454c550186162d8788251ae1613d89 av_one_full  avia-builder-el-9  el_after_av_section  el_before_av_one_full  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1abcn-54badf3914a763678acd93b3028ef1d0\">\n#top .hr.hr-invisible.av-1abcn-54badf3914a763678acd93b3028ef1d0{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-1abcn-54badf3914a763678acd93b3028ef1d0 hr-invisible  avia-builder-el-10  el_before_av_textblock  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-liabxhtl-aff384d113be88088378777cb7fd3e16\">\n#top .av_textblock_section.av-liabxhtl-aff384d113be88088378777cb7fd3e16 .avia_textblock{\nfont-size:15px;\n}\n<\/style>\n<section  class='av_textblock_section av-liabxhtl-aff384d113be88088378777cb7fd3e16 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\"><strong>Il CICSU si trova presso il Campus Pierre e Marie Curie<br \/>\n(4, place Jussieu), nel 5\u00b0 arrondissement di Parigi,<br \/>\nnel cuore del Quartiere Latino.<br \/>\n<\/strong><\/p>\n<h4 style=\"text-align: center;\">\u00c8 raggiungibile con le linee 7 e 10 della metropolitana.<\/h4>\n<\/div><\/section><br \/>\n<div  class='avia-buttonrow-wrap av-liac3nzm-24c6ef5b9bd3cf5a710138f0748e0e17 avia-buttonrow-center  avia-builder-el-12  el_after_av_textblock  el_before_av_hr '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-liac2ap5-4d897759d41a06dfbefe3bfda8c34c96\">\n#top #wrap_all .avia-button.av-liac2ap5-4d897759d41a06dfbefe3bfda8c34c96{\nmargin-bottom:5px;\nmargin-right:3px;\nmargin-left:3px;\n}\n<\/style>\n<a href=\"https:\/\/www.hotelaparis.com\/hotel-paris-sur-lignes-metro-rer-tram\/ligne-7-villejuif-louis-aragon-la-courneuve-8-mai-1945.html\" class=\"avia-button av-liac2ap5-4d897759d41a06dfbefe3bfda8c34c96 avia-icon_select-no avia-size-large avia-color-theme-color-highlight\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Elenco degli hotel sulla linea 7 \"><span class='avia_iconbox_title' >Elenco degli hotel sulla linea 7 <\/span><\/a>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-liac3glg-e2754a0d3102b00e3d20f5f4c4981bcb\">\n#top #wrap_all .avia-button.av-liac3glg-e2754a0d3102b00e3d20f5f4c4981bcb{\nbackground-color:#f0593e;\nborder-color:#f0593e;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\nmargin-bottom:5px;\nmargin-right:3px;\nmargin-left:3px;\n}\n<\/style>\n<a href=\"https:\/\/www.hotelaparis.com\/hotel-paris-sur-lignes-metro-rer-tram\/ligne-10-gare-d-austerlitz-boulogne-pont-de-saint-cloud.html\" class=\"avia-button av-liac3glg-e2754a0d3102b00e3d20f5f4c4981bcb avia-icon_select-no avia-size-large\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Elenco degli hotel sulla linea 10\"><span class='avia_iconbox_title' >Elenco degli hotel sulla linea 10<\/span><\/a>\n<\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-liub7zpa-a27ed4b48f6b09a87addbadf4736b83a\">\n#top .hr.hr-invisible.av-liub7zpa-a27ed4b48f6b09a87addbadf4736b83a{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-liub7zpa-a27ed4b48f6b09a87addbadf4736b83a hr-invisible  avia-builder-el-13  el_after_av_buttonrow  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div><\/p>\n<div  class='flex_column av-9p2yr-84f99e256fcc38c4e4af05df3a57e6f9 av_one_full  avia-builder-el-14  el_after_av_one_full  avia-builder-el-last  first flex_column_div  column-top-margin'     ><p><div  class='hr av-13gtn-4d393535c0d80b2b0d97c2a2f6795a33 hr-default  avia-builder-el-15  el_before_av_heading  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8l7gz-5eea425f3adf3cb7f1447eb55943a451\">\n#top .av-special-heading.av-8l7gz-5eea425f3adf3cb7f1447eb55943a451{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-8l7gz-5eea425f3adf3cb7f1447eb55943a451 .av-special-heading-tag .heading-char{\nfont-size:51px;\n}\n.av-special-heading.av-8l7gz-5eea425f3adf3cb7f1447eb55943a451 .av-subheading{\nfont-size:25px;\n}\n<\/style>\n<div  class='av-special-heading av-8l7gz-5eea425f3adf3cb7f1447eb55943a451 av-special-heading-h2 blockquote elegant-quote elegant-centered  avia-builder-el-16  el_after_av_hr  el_before_av_partner '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  ><span class=\"heading-wrap\">Partner dell\u2019evento<\/span><\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='avia-logo-element-container av-7woiv-0b1122fefff2904655702a4a9017ab73 av-border-deactivate avia-logo-slider avia-content-slider avia-smallarrow-slider avia-content-slider-active noHover avia-content-slider-even  avia-builder-el-17  el_after_av_heading  el_before_av_partner  av-slideshow-ui av-control-default av-nav-arrows-visible av-nav-dots-visible av-no-slider-navigation av-slideshow-manual av-loop-once av-loop-manual-endless avia-content-slider1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:&quot;&quot;,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"><div class='avia-smallarrow-slider-heading  no-logo-slider-heading '><div class='new-special-heading'>&nbsp;<\/div><\/div><div class=\"avia-content-slider-inner\"><div class=\"slide-entry-wrap\"><div  class='slide-entry av-7i88b-397d8d5a0bbb7d431fdf10306af4e899 flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-1 slide-parity-odd  first'><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aiep-logo.jpg\" class=\"wp-image-721 avia-img-lazy-loading-not-721 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aiep-logo.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aiep-logo-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aiep-logo-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aiep-logo-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-6sfdf-28df0863979c933c2ac246ecadfec9cb flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-2 slide-parity-even  '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aphp.jpg\" class=\"wp-image-722 avia-img-lazy-loading-not-722 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aphp.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aphp-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aphp-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/aphp-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-mnt3-c4613e420f35c37f7f83b4ee89afd31e flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-3 slide-parity-odd  '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/babel-copes.jpg\" class=\"wp-image-723 avia-img-lazy-loading-not-723 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/babel-copes.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/babel-copes-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/babel-copes-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/babel-copes-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-5kup7-b77a690542377e431a8490d68e0f08a3 flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-4 slide-parity-even  '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/cesp-logo.jpg\" class=\"wp-image-724 avia-img-lazy-loading-not-724 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/cesp-logo.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/cesp-logo-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/cesp-logo-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/cesp-logo-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-5ar73-7ae0c9e305504f17890da65321b096fa flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-5 slide-parity-odd  '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ice-logo.jpg\" class=\"wp-image-725 avia-img-lazy-loading-not-725 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ice-logo.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ice-logo-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ice-logo-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ice-logo-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-4o9pf-b0692dffd6f36b3dca8c40f4ee7a354e flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-6 slide-parity-even post-entry-last '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-copes.jpg\" class=\"wp-image-726 avia-img-lazy-loading-not-726 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-copes.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-copes-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-copes-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-copes-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><br \/>\n<div  class='avia-logo-element-container av-4061b-07ca93774cd12c0fdf4e174b5cccfdc8 av-border-deactivate avia-logo-slider avia-content-slider avia-smallarrow-slider avia-content-slider-active noHover avia-content-slider-even  avia-builder-el-18  el_after_av_partner  avia-builder-el-last  av-slideshow-ui av-control-default av-nav-arrows-visible av-nav-dots-visible av-no-slider-navigation av-slideshow-manual av-loop-once av-loop-manual-endless avia-content-slider2' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:&quot;&quot;,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"><div class='avia-smallarrow-slider-heading  no-logo-slider-heading '><div class='new-special-heading'>&nbsp;<\/div><\/div><div class=\"avia-content-slider-inner\"><div class=\"slide-entry-wrap\"><div  class='slide-entry av-3ha93-da5fc87b368801ac1fb729dafc3a8088 flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-1 slide-parity-odd  first'><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-utrpp.jpg\" class=\"wp-image-727 avia-img-lazy-loading-not-727 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-utrpp.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-utrpp-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-utrpp-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/logo-utrpp-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-2q9c3-cffd9bafea763b0e4561e2f94647377f flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-2 slide-parity-even  '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ville-de-paris.jpg\" class=\"wp-image-731 avia-img-lazy-loading-not-731 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ville-de-paris.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ville-de-paris-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ville-de-paris-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/ville-de-paris-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-281mj-19f9029b2da3a918904999228d5e0538 flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-3 slide-parity-odd  '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/pcpp.jpg\" class=\"wp-image-729 avia-img-lazy-loading-not-729 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/pcpp.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/pcpp-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/pcpp-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/pcpp-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-1q89n-fc95c2352da2de8deb563b29db711f6e flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-4 slide-parity-even  '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/maison-de-solenn.jpg\" class=\"wp-image-728 avia-img-lazy-loading-not-728 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/maison-de-solenn.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/maison-de-solenn-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/maison-de-solenn-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/maison-de-solenn-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-2lw7-6d39aff548085db638d6314b9b81c106 flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-5 slide-parity-odd  '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/03\/Logo-revue-l-autre.png\" class=\"wp-image-736 avia-img-lazy-loading-not-736 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/03\/Logo-revue-l-autre.png 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/03\/Logo-revue-l-autre-80x80.png 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/03\/Logo-revue-l-autre-36x36.png 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/03\/Logo-revue-l-autre-180x180.png 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div  class='slide-entry av-2lw7-1-ca4aa4bc640f22ea5e547711870b5752 flex_column no_margin av_one_sixth real-thumbnail post-entry slide-entry-overview slide-loop-6 slide-parity-even post-entry-last '><img decoding=\"async\" fetchpriority=\"high\" width=\"300\" height=\"300\" src=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/uni-de-paris.jpg\" class=\"wp-image-730 avia-img-lazy-loading-not-730 attachment-no scaling size-no scaling\" alt=\"\" srcset=\"https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/uni-de-paris.jpg 300w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/uni-de-paris-80x80.jpg 80w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/uni-de-paris-36x36.jpg 36w, https:\/\/centre-babel.fr\/colloque-babel\/wp-content\/uploads\/2023\/02\/uni-de-paris-180x180.jpg 180w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-802","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/centre-babel.fr\/colloque-babel\/it\/wp-json\/wp\/v2\/pages\/802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centre-babel.fr\/colloque-babel\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/centre-babel.fr\/colloque-babel\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/centre-babel.fr\/colloque-babel\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/centre-babel.fr\/colloque-babel\/it\/wp-json\/wp\/v2\/comments?post=802"}],"version-history":[{"count":12,"href":"https:\/\/centre-babel.fr\/colloque-babel\/it\/wp-json\/wp\/v2\/pages\/802\/revisions"}],"predecessor-version":[{"id":1176,"href":"https:\/\/centre-babel.fr\/colloque-babel\/it\/wp-json\/wp\/v2\/pages\/802\/revisions\/1176"}],"wp:attachment":[{"href":"https:\/\/centre-babel.fr\/colloque-babel\/it\/wp-json\/wp\/v2\/media?parent=802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}